{"id":962,"date":"2024-04-03T16:37:13","date_gmt":"2024-04-03T14:37:13","guid":{"rendered":"https:\/\/tusta.com.ar\/?post_type=product&#038;p=962"},"modified":"2026-07-13T09:29:05","modified_gmt":"2026-07-13T12:29:05","slug":"hidromasajeador-blanco-f-v-1-1-2","status":"publish","type":"product","link":"https:\/\/tusta.com.ar\/index.php\/producto\/hidromasajeador-blanco-f-v-1-1-2\/","title":{"rendered":"Hidromasajeador Blanco F.V 1 1\/2&#8243; Vulcano"},"content":{"rendered":"<div align=\"center\">\n<div id=\"lodeladerecha\" align=\"left\">\n<div align=\"left\">Hidromasajeador para piscinas de fibra de vidrio, con aro desmontable blanco, y cuerpo con rosca macho de 1 1\/2&#8243;. Dise\u00f1ados especialmente para proporcionar al usuario una grata sensaci\u00f3n de bienestar y acci\u00f3n terap\u00e9utica, mediante un chorro o jet a presi\u00f3n que se puede combinar con aire, mediante un ca\u00f1o con sombrero venturi, o instalando una bomba sopladora.<\/div>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Hidromasajeador para piscinas de fibra de vidrio, con aro desmontable blanco, y cuerpo con rosca macho de 1 1\/2&#8243;. Dise\u00f1ados especialmente para proporcionar al usuario una grata sensaci\u00f3n de bienestar y acci\u00f3n terap\u00e9utica, mediante un chorro o jet a presi\u00f3n que se puede combinar con aire, mediante un ca\u00f1o con sombrero venturi, o instalando una bomba sopladora.<\/p>\n","protected":false},"featured_media":1016,"comment_status":"open","ping_status":"closed","template":"","meta":{"_eb_attr":""},"product_brand":[],"product_cat":[75,55],"product_tag":[112],"class_list":["post-962","product","type-product","status-publish","has-post-thumbnail","product_cat-hidromasajeadores","product_cat-piscina","product_tag-vulcano","first","instock","shipping-taxable","purchasable","product-type-simple"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Hidromasajeador Blanco F.V 1 1\/2&quot; Vulcano - Tusta<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/tusta.com.ar\/index.php\/producto\/hidromasajeador-blanco-f-v-1-1-2\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Hidromasajeador Blanco F.V 1 1\/2&quot; Vulcano - Tusta\" \/>\n<meta property=\"og:description\" content=\"Hidromasajeador para piscinas de fibra de vidrio, con aro desmontable blanco, y cuerpo con rosca macho de 1 1\/2&#8243;. Dise\u00f1ados especialmente para proporcionar al usuario una grata sensaci\u00f3n de bienestar y acci\u00f3n terap\u00e9utica, mediante un chorro o jet a presi\u00f3n que se puede combinar con aire, mediante un ca\u00f1o con sombrero venturi, o instalando una bomba sopladora.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/tusta.com.ar\/index.php\/producto\/hidromasajeador-blanco-f-v-1-1-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Tusta\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-13T12:29:05+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/tusta.com.ar\/wp-content\/uploads\/2024\/04\/Hidromasajeador-Blanco-F.V-1-1-2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"1200\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/tusta.com.ar\\\/index.php\\\/producto\\\/hidromasajeador-blanco-f-v-1-1-2\\\/\",\"url\":\"https:\\\/\\\/tusta.com.ar\\\/index.php\\\/producto\\\/hidromasajeador-blanco-f-v-1-1-2\\\/\",\"name\":\"Hidromasajeador Blanco F.V 1 1\\\/2\\\" Vulcano - Tusta\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/tusta.com.ar\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/tusta.com.ar\\\/index.php\\\/producto\\\/hidromasajeador-blanco-f-v-1-1-2\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/tusta.com.ar\\\/index.php\\\/producto\\\/hidromasajeador-blanco-f-v-1-1-2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/tusta.com.ar\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/Hidromasajeador-Blanco-F.V-1-1-2.jpg\",\"datePublished\":\"2024-04-03T14:37:13+00:00\",\"dateModified\":\"2026-07-13T12:29:05+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/tusta.com.ar\\\/index.php\\\/producto\\\/hidromasajeador-blanco-f-v-1-1-2\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/tusta.com.ar\\\/index.php\\\/producto\\\/hidromasajeador-blanco-f-v-1-1-2\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/tusta.com.ar\\\/index.php\\\/producto\\\/hidromasajeador-blanco-f-v-1-1-2\\\/#primaryimage\",\"url\":\"https:\\\/\\\/tusta.com.ar\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/Hidromasajeador-Blanco-F.V-1-1-2.jpg\",\"contentUrl\":\"https:\\\/\\\/tusta.com.ar\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/Hidromasajeador-Blanco-F.V-1-1-2.jpg\",\"width\":1200,\"height\":1200},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/tusta.com.ar\\\/index.php\\\/producto\\\/hidromasajeador-blanco-f-v-1-1-2\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/tusta.com.ar\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Productos\",\"item\":\"https:\\\/\\\/tusta.com.ar\\\/index.php\\\/productos\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Hidromasajeador Blanco F.V 1 1\\\/2&#8243; Vulcano\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/tusta.com.ar\\\/#website\",\"url\":\"https:\\\/\\\/tusta.com.ar\\\/\",\"name\":\"Tusta\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/tusta.com.ar\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/tusta.com.ar\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/tusta.com.ar\\\/#organization\",\"name\":\"Tusta\",\"url\":\"https:\\\/\\\/tusta.com.ar\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/tusta.com.ar\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/tusta.com.ar\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/tuschic_Mesa-de-trabajo-1.webp\",\"contentUrl\":\"https:\\\/\\\/tusta.com.ar\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/tuschic_Mesa-de-trabajo-1.webp\",\"width\":250,\"height\":100,\"caption\":\"Tusta\"},\"image\":{\"@id\":\"https:\\\/\\\/tusta.com.ar\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/instagram.com\\\/tusta_ok\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Hidromasajeador Blanco F.V 1 1\/2\" Vulcano - Tusta","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/tusta.com.ar\/index.php\/producto\/hidromasajeador-blanco-f-v-1-1-2\/","og_locale":"es_ES","og_type":"article","og_title":"Hidromasajeador Blanco F.V 1 1\/2\" Vulcano - Tusta","og_description":"Hidromasajeador para piscinas de fibra de vidrio, con aro desmontable blanco, y cuerpo con rosca macho de 1 1\/2&#8243;. Dise\u00f1ados especialmente para proporcionar al usuario una grata sensaci\u00f3n de bienestar y acci\u00f3n terap\u00e9utica, mediante un chorro o jet a presi\u00f3n que se puede combinar con aire, mediante un ca\u00f1o con sombrero venturi, o instalando una bomba sopladora.","og_url":"https:\/\/tusta.com.ar\/index.php\/producto\/hidromasajeador-blanco-f-v-1-1-2\/","og_site_name":"Tusta","article_modified_time":"2026-07-13T12:29:05+00:00","og_image":[{"width":1200,"height":1200,"url":"https:\/\/tusta.com.ar\/wp-content\/uploads\/2024\/04\/Hidromasajeador-Blanco-F.V-1-1-2.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/tusta.com.ar\/index.php\/producto\/hidromasajeador-blanco-f-v-1-1-2\/","url":"https:\/\/tusta.com.ar\/index.php\/producto\/hidromasajeador-blanco-f-v-1-1-2\/","name":"Hidromasajeador Blanco F.V 1 1\/2\" Vulcano - Tusta","isPartOf":{"@id":"https:\/\/tusta.com.ar\/#website"},"primaryImageOfPage":{"@id":"https:\/\/tusta.com.ar\/index.php\/producto\/hidromasajeador-blanco-f-v-1-1-2\/#primaryimage"},"image":{"@id":"https:\/\/tusta.com.ar\/index.php\/producto\/hidromasajeador-blanco-f-v-1-1-2\/#primaryimage"},"thumbnailUrl":"https:\/\/tusta.com.ar\/wp-content\/uploads\/2024\/04\/Hidromasajeador-Blanco-F.V-1-1-2.jpg","datePublished":"2024-04-03T14:37:13+00:00","dateModified":"2026-07-13T12:29:05+00:00","breadcrumb":{"@id":"https:\/\/tusta.com.ar\/index.php\/producto\/hidromasajeador-blanco-f-v-1-1-2\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/tusta.com.ar\/index.php\/producto\/hidromasajeador-blanco-f-v-1-1-2\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/tusta.com.ar\/index.php\/producto\/hidromasajeador-blanco-f-v-1-1-2\/#primaryimage","url":"https:\/\/tusta.com.ar\/wp-content\/uploads\/2024\/04\/Hidromasajeador-Blanco-F.V-1-1-2.jpg","contentUrl":"https:\/\/tusta.com.ar\/wp-content\/uploads\/2024\/04\/Hidromasajeador-Blanco-F.V-1-1-2.jpg","width":1200,"height":1200},{"@type":"BreadcrumbList","@id":"https:\/\/tusta.com.ar\/index.php\/producto\/hidromasajeador-blanco-f-v-1-1-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/tusta.com.ar\/"},{"@type":"ListItem","position":2,"name":"Productos","item":"https:\/\/tusta.com.ar\/index.php\/productos\/"},{"@type":"ListItem","position":3,"name":"Hidromasajeador Blanco F.V 1 1\/2&#8243; Vulcano"}]},{"@type":"WebSite","@id":"https:\/\/tusta.com.ar\/#website","url":"https:\/\/tusta.com.ar\/","name":"Tusta","description":"","publisher":{"@id":"https:\/\/tusta.com.ar\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/tusta.com.ar\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/tusta.com.ar\/#organization","name":"Tusta","url":"https:\/\/tusta.com.ar\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/tusta.com.ar\/#\/schema\/logo\/image\/","url":"https:\/\/tusta.com.ar\/wp-content\/uploads\/2026\/07\/tuschic_Mesa-de-trabajo-1.webp","contentUrl":"https:\/\/tusta.com.ar\/wp-content\/uploads\/2026\/07\/tuschic_Mesa-de-trabajo-1.webp","width":250,"height":100,"caption":"Tusta"},"image":{"@id":"https:\/\/tusta.com.ar\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/instagram.com\/tusta_ok"]}]}},"_links":{"self":[{"href":"https:\/\/tusta.com.ar\/index.php\/wp-json\/wp\/v2\/product\/962","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tusta.com.ar\/index.php\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/tusta.com.ar\/index.php\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/tusta.com.ar\/index.php\/wp-json\/wp\/v2\/comments?post=962"}],"version-history":[{"count":3,"href":"https:\/\/tusta.com.ar\/index.php\/wp-json\/wp\/v2\/product\/962\/revisions"}],"predecessor-version":[{"id":2157,"href":"https:\/\/tusta.com.ar\/index.php\/wp-json\/wp\/v2\/product\/962\/revisions\/2157"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/tusta.com.ar\/index.php\/wp-json\/wp\/v2\/media\/1016"}],"wp:attachment":[{"href":"https:\/\/tusta.com.ar\/index.php\/wp-json\/wp\/v2\/media?parent=962"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/tusta.com.ar\/index.php\/wp-json\/wp\/v2\/product_brand?post=962"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/tusta.com.ar\/index.php\/wp-json\/wp\/v2\/product_cat?post=962"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/tusta.com.ar\/index.php\/wp-json\/wp\/v2\/product_tag?post=962"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}